{"id":2059,"date":"2021-03-30T13:08:29","date_gmt":"2021-03-30T05:08:29","guid":{"rendered":"http:\/\/www.kxtxlogistic.com\/?page_id=2059"},"modified":"2021-03-30T15:06:39","modified_gmt":"2021-03-30T07:06:39","slug":"newpeople","status":"publish","type":"page","link":"http:\/\/www.kxtxlogistic.com\/index.php\/newpeople\/","title":{"rendered":"\u4eba\u624d\u62db\u8058"},"content":{"rendered":"\n<img class=\"banner\" src=\"img\/job-banner.png\" alt=\"\" srcset=\"\">\n    <div class=\"title\">\u6c42\u804c\u4eba\u5458\u4fe1\u606f\u767b\u8bb0<\/div>\n    <div class=\"border\"><\/div>\n    <div class=\"jobModel\">\n        <div>\n            <img class=\"jobLeft\" src=\"http:\/\/www.kxtxlogistic.com\/wp-content\/uploads\/2021\/03\/workroom.png\" alt=\"\" srcset=\"\">\n            <div class=\"work-environment\">\u529e\u516c\u73af\u5883<\/div>\n        <\/div>\n        <div class=\"left-border\"><\/div>\n        <div class=\"jobRightBox\">\n           <div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f2079-o1\" lang=\"zh-CN\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/2059#wpcf7-f2079-o1\" method=\"post\" class=\"wpcf7-form init\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2079\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.6.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2079-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> \u59d3\u540d<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u7535\u8bdd<br \/>\n    <span class=\"wpcf7-form-control-wrap your-tel\"><input type=\"tel\" name=\"your-tel\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u90ae\u7bb1<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u6c42\u804c\u610f\u5411<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><span class=\"wpcf7-form-control-wrap file-350\"><input type=\"file\" name=\"file-350\" size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.jpeg,.png,.gif,.pdf,.doc,.docx,.ppt,.pptx,.odt,.avi,.ogg,.m4a,.mov,.mp3,.mp4,.mpg,.wav,.wmv\" aria-invalid=\"false\" \/><\/span><\/p>\n<p><input type=\"submit\" value=\"\u63d0\u4ea4\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n        <\/div>\n    <\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u6c42\u804c\u4eba\u5458\u4fe1\u606f\u767b\u8bb0 \u529e\u516c\u73af\u5883<\/p>\n","protected":false},"author":1,"featured_media":2075,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/www.kxtxlogistic.com\/index.php\/wp-json\/wp\/v2\/pages\/2059"}],"collection":[{"href":"http:\/\/www.kxtxlogistic.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.kxtxlogistic.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.kxtxlogistic.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.kxtxlogistic.com\/index.php\/wp-json\/wp\/v2\/comments?post=2059"}],"version-history":[{"count":12,"href":"http:\/\/www.kxtxlogistic.com\/index.php\/wp-json\/wp\/v2\/pages\/2059\/revisions"}],"predecessor-version":[{"id":2080,"href":"http:\/\/www.kxtxlogistic.com\/index.php\/wp-json\/wp\/v2\/pages\/2059\/revisions\/2080"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.kxtxlogistic.com\/index.php\/wp-json\/wp\/v2\/media\/2075"}],"wp:attachment":[{"href":"http:\/\/www.kxtxlogistic.com\/index.php\/wp-json\/wp\/v2\/media?parent=2059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}